{"id":2406,"date":"2009-06-15T00:00:00","date_gmt":"2009-06-15T00:00:00","guid":{"rendered":"https:\/\/www.visualarq.com\/support\/tips\/2406\/when-i-open-a-new-drawing-the-visualarq-templates-are-not-displayed-in-the-templates-dialog-box-how-can-i-make-them-appear\/"},"modified":"2021-06-16T11:38:34","modified_gmt":"2021-06-16T11:38:34","slug":"when-i-open-a-new-drawing-the-visualarq-templates-are-not-displayed-in-the-templates-dialog-box-how-can-i-make-them-appear","status":"publish","type":"tip","link":"https:\/\/www.visualarq.com\/de\/support\/tip\/when-i-open-a-new-drawing-the-visualarq-templates-are-not-displayed-in-the-templates-dialog-box-how-can-i-make-them-appear\/","title":{"rendered":"Wenn ich eine neue Zeichnung \u00f6ffne, werden die VisualARQ-Vorlagen nicht im Dialogfenster der Vorlagen angezeigt&#8230; Wie kann ich sie sichtbar machen?"},"content":{"rendered":"Wenn Sie eine neue Datei \u00f6ffnen und die VisualARQ-Vorlagen nicht im Dialogfenster der verf\u00fcgbaren Vorlagen auftauchen, kann es daf\u00fcr zwei Gr\u00fcnde geben:\n\n<hr class=\"separator\">\n<h2>Dateien befinden sich nicht im selben Ordner wie die Rhino-Vorlagen<\/h2>\nIn diesem Fall kopieren Sie die VisualARQ-Vorlagen einfach in den Ordner, in dem auch die Rhino-Vorlagen gespeichert sind.\n\nDer entsprechende Ordner ist in Rhino unter Optionen > Dateien > Vorlagedateien > Standort angegeben.\n\nDie folgenden VisualARQ-Vorlagen werden bei der Installation von VisualARQ im unten stehenden Ordner erstellt:\n<ul>\n \t<li style=\"list-style-type: none;\">\n<ul>\n \t<li><strong>VisualARQ &#8211; Meter.3dm<\/strong><\/li>\n \t<li><strong>VisualARQ &#8211; Millimeter.3dm<\/strong><\/li>\n \t<li><strong>VisualARQ &#8211; Fu\u00df.3dm<\/strong><\/li>\n \t<li><strong>VisualARQ &#8211; Zoll.3dm<\/strong><\/li>\n<\/ul>\n<\/li>\n<\/ul>\n<ul>\n \t<li><b>In Rhino 7:<\/b><\/li>\n<\/ul>\n<code>C:\\Users\\<em>\"Benutzername\"<\/em>\\AppData\\Roaming\\McNeel\\Rhinoceros\\7.0\\Localization\\en-US\\Template Files<\/code>\n<ul>\n \t<li><b>In Rhino 6:<\/b><\/li>\n<\/ul>\n<code>C:\\Users\\<em>\"Benutzername\"<\/em>\\AppData\\Roaming\\McNeel\\Rhinoceros\\6.0\\Localization\\en-US\\Template Files<\/code>\n<ul>\n \t<li><b>In Rhino 5 (32- und 64-Bit):<\/b><\/li>\n<\/ul>\n<code>C:\\Users\\<em>\"Benutzername\"<\/em>\\AppData\\Roaming\\McNeel\\Rhinoceros\\5.0\\Localization\\en-US\\Template Files<\/code>\n\n(Diese Verzeichnisse entspechen einer deutschen Installation. Wenn Sie eine deutsche Version besitzen, steht hier &#8222;de-DE&#8220;. Anderssprachige Versionen haben dementsprechend abweichende Codes.\n<hr class=\"separator\">\n<h2>VisualARQ wurde von einem anderen Benutzer installiert<\/h2>\nMelden Sie sich in diesem Fall auf dem Computer mit dem Benutzerkonto an, unter dem auch die Installation durchgef\u00fchrt wurde, kopieren Sie die Vorlagendateien (und die Werkzeugleistendatei) an einen Ort, auf den Sie auch von Ihrem Benutzerkonto aus zugreifen k\u00f6nnen, melden Sie sich wieder ab und speichern Sie die Dateien in Ihrem Benutzerkonto dort, wo auch die Rhino-Vorlagen gespeichert sind.","protected":false},"featured_media":0,"parent":0,"menu_order":0,"template":"","meta":{"_et_pb_use_builder":"","_et_pb_old_content":"","_et_gb_content_width":"","footnotes":"","_members_access_role":[],"_members_access_error":""},"tipgroup":[99],"class_list":["post-2406","tip","type-tip","status-publish","hentry","tipgroup-object-lib-de"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Wenn ich eine neue Zeichnung \u00f6ffne, werden die VisualARQ-Vorlagen nicht im Dialogfenster der Vorlagen angezeigt... Wie kann ich sie sichtbar machen? - VisualARQ<\/title>\n<meta name=\"description\" content=\"Wenn Vorlagen fehlen, m\u00fcssen Sie m\u00f6glicherweise die VisualARQ-Vorlagendateien in den Ordner kopieren, in dem die Rhino-Vorlagen enthalten sind.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.visualarq.com\/de\/support\/tip\/when-i-open-a-new-drawing-the-visualarq-templates-are-not-displayed-in-the-templates-dialog-box-how-can-i-make-them-appear\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Wenn ich eine neue Zeichnung \u00f6ffne, werden die VisualARQ-Vorlagen nicht im Dialogfenster der Vorlagen angezeigt... Wie kann ich sie sichtbar machen? - VisualARQ\" \/>\n<meta property=\"og:description\" content=\"Wenn Vorlagen fehlen, m\u00fcssen Sie m\u00f6glicherweise die VisualARQ-Vorlagendateien in den Ordner kopieren, in dem die Rhino-Vorlagen enthalten sind.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.visualarq.com\/de\/support\/tip\/when-i-open-a-new-drawing-the-visualarq-templates-are-not-displayed-in-the-templates-dialog-box-how-can-i-make-them-appear\/\" \/>\n<meta property=\"og:site_name\" content=\"VisualARQ\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/visualarq\" \/>\n<meta property=\"article:modified_time\" content=\"2021-06-16T11:38:34+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@VisualARQ\" \/>\n<meta name=\"twitter:label1\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data1\" content=\"1\u00a0Minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.visualarq.com\\\/de\\\/support\\\/tip\\\/when-i-open-a-new-drawing-the-visualarq-templates-are-not-displayed-in-the-templates-dialog-box-how-can-i-make-them-appear\\\/\",\"url\":\"https:\\\/\\\/www.visualarq.com\\\/de\\\/support\\\/tip\\\/when-i-open-a-new-drawing-the-visualarq-templates-are-not-displayed-in-the-templates-dialog-box-how-can-i-make-them-appear\\\/\",\"name\":\"Wenn ich eine neue Zeichnung \u00f6ffne, werden die VisualARQ-Vorlagen nicht im Dialogfenster der Vorlagen angezeigt... Wie kann ich sie sichtbar machen? - VisualARQ\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.visualarq.com\\\/de\\\/#website\"},\"datePublished\":\"2009-06-15T00:00:00+00:00\",\"dateModified\":\"2021-06-16T11:38:34+00:00\",\"description\":\"Wenn Vorlagen fehlen, m\u00fcssen Sie m\u00f6glicherweise die VisualARQ-Vorlagendateien in den Ordner kopieren, in dem die Rhino-Vorlagen enthalten sind.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.visualarq.com\\\/de\\\/support\\\/tip\\\/when-i-open-a-new-drawing-the-visualarq-templates-are-not-displayed-in-the-templates-dialog-box-how-can-i-make-them-appear\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.visualarq.com\\\/de\\\/support\\\/tip\\\/when-i-open-a-new-drawing-the-visualarq-templates-are-not-displayed-in-the-templates-dialog-box-how-can-i-make-them-appear\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.visualarq.com\\\/de\\\/support\\\/tip\\\/when-i-open-a-new-drawing-the-visualarq-templates-are-not-displayed-in-the-templates-dialog-box-how-can-i-make-them-appear\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.visualarq.com\\\/de\\\/home\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Tips\",\"item\":\"https:\\\/\\\/www.visualarq.com\\\/de\\\/support\\\/tip\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Wenn ich eine neue Zeichnung \u00f6ffne, werden die VisualARQ-Vorlagen nicht im Dialogfenster der Vorlagen angezeigt&#8230; Wie kann ich sie sichtbar machen?\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.visualarq.com\\\/de\\\/#website\",\"url\":\"https:\\\/\\\/www.visualarq.com\\\/de\\\/\",\"name\":\"VisualARQ\",\"description\":\"Flexible BIM for Rhino\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.visualarq.com\\\/de\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Wenn ich eine neue Zeichnung \u00f6ffne, werden die VisualARQ-Vorlagen nicht im Dialogfenster der Vorlagen angezeigt... Wie kann ich sie sichtbar machen? - VisualARQ","description":"Wenn Vorlagen fehlen, m\u00fcssen Sie m\u00f6glicherweise die VisualARQ-Vorlagendateien in den Ordner kopieren, in dem die Rhino-Vorlagen enthalten sind.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.visualarq.com\/de\/support\/tip\/when-i-open-a-new-drawing-the-visualarq-templates-are-not-displayed-in-the-templates-dialog-box-how-can-i-make-them-appear\/","og_locale":"de_DE","og_type":"article","og_title":"Wenn ich eine neue Zeichnung \u00f6ffne, werden die VisualARQ-Vorlagen nicht im Dialogfenster der Vorlagen angezeigt... Wie kann ich sie sichtbar machen? - VisualARQ","og_description":"Wenn Vorlagen fehlen, m\u00fcssen Sie m\u00f6glicherweise die VisualARQ-Vorlagendateien in den Ordner kopieren, in dem die Rhino-Vorlagen enthalten sind.","og_url":"https:\/\/www.visualarq.com\/de\/support\/tip\/when-i-open-a-new-drawing-the-visualarq-templates-are-not-displayed-in-the-templates-dialog-box-how-can-i-make-them-appear\/","og_site_name":"VisualARQ","article_publisher":"https:\/\/www.facebook.com\/visualarq","article_modified_time":"2021-06-16T11:38:34+00:00","twitter_card":"summary_large_image","twitter_site":"@VisualARQ","twitter_misc":{"Gesch\u00e4tzte Lesezeit":"1\u00a0Minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.visualarq.com\/de\/support\/tip\/when-i-open-a-new-drawing-the-visualarq-templates-are-not-displayed-in-the-templates-dialog-box-how-can-i-make-them-appear\/","url":"https:\/\/www.visualarq.com\/de\/support\/tip\/when-i-open-a-new-drawing-the-visualarq-templates-are-not-displayed-in-the-templates-dialog-box-how-can-i-make-them-appear\/","name":"Wenn ich eine neue Zeichnung \u00f6ffne, werden die VisualARQ-Vorlagen nicht im Dialogfenster der Vorlagen angezeigt... Wie kann ich sie sichtbar machen? - VisualARQ","isPartOf":{"@id":"https:\/\/www.visualarq.com\/de\/#website"},"datePublished":"2009-06-15T00:00:00+00:00","dateModified":"2021-06-16T11:38:34+00:00","description":"Wenn Vorlagen fehlen, m\u00fcssen Sie m\u00f6glicherweise die VisualARQ-Vorlagendateien in den Ordner kopieren, in dem die Rhino-Vorlagen enthalten sind.","breadcrumb":{"@id":"https:\/\/www.visualarq.com\/de\/support\/tip\/when-i-open-a-new-drawing-the-visualarq-templates-are-not-displayed-in-the-templates-dialog-box-how-can-i-make-them-appear\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.visualarq.com\/de\/support\/tip\/when-i-open-a-new-drawing-the-visualarq-templates-are-not-displayed-in-the-templates-dialog-box-how-can-i-make-them-appear\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.visualarq.com\/de\/support\/tip\/when-i-open-a-new-drawing-the-visualarq-templates-are-not-displayed-in-the-templates-dialog-box-how-can-i-make-them-appear\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.visualarq.com\/de\/home\/"},{"@type":"ListItem","position":2,"name":"Tips","item":"https:\/\/www.visualarq.com\/de\/support\/tip\/"},{"@type":"ListItem","position":3,"name":"Wenn ich eine neue Zeichnung \u00f6ffne, werden die VisualARQ-Vorlagen nicht im Dialogfenster der Vorlagen angezeigt&#8230; Wie kann ich sie sichtbar machen?"}]},{"@type":"WebSite","@id":"https:\/\/www.visualarq.com\/de\/#website","url":"https:\/\/www.visualarq.com\/de\/","name":"VisualARQ","description":"Flexible BIM for Rhino","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.visualarq.com\/de\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"}]}},"_links":{"self":[{"href":"https:\/\/www.visualarq.com\/de\/wp-json\/wp\/v2\/tip\/2406","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.visualarq.com\/de\/wp-json\/wp\/v2\/tip"}],"about":[{"href":"https:\/\/www.visualarq.com\/de\/wp-json\/wp\/v2\/types\/tip"}],"version-history":[{"count":0,"href":"https:\/\/www.visualarq.com\/de\/wp-json\/wp\/v2\/tip\/2406\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.visualarq.com\/de\/wp-json\/wp\/v2\/media?parent=2406"}],"wp:term":[{"taxonomy":"tipgroup","embeddable":true,"href":"https:\/\/www.visualarq.com\/de\/wp-json\/wp\/v2\/tipgroup?post=2406"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}