{"id":2350,"date":"2012-05-08T00:00:00","date_gmt":"2012-05-08T00:00:00","guid":{"rendered":"https:\/\/www.visualarq.com\/support\/tips\/2350\/how-can-i-create-and-select-openings\/"},"modified":"2019-04-23T12:57:38","modified_gmt":"2019-04-23T12:57:38","slug":"how-can-i-create-and-select-openings","status":"publish","type":"tip","link":"https:\/\/www.visualarq.com\/fr\/support\/tip\/how-can-i-create-and-select-openings\/","title":{"rendered":"Comment cr\u00e9er et s\u00e9lectionner des ouvertures"},"content":{"rendered":"<p>Le fonctionnement d&rsquo;une ouverture est le m\u00eame que celui d&rsquo;une fen\u00eatre ou une porte.<\/p>\n<p>\u00c9tapes pour cr\u00e9er une nouvelle ouverture :<\/p>\n<ol>\n<li>Lancer la commande <strong>vaOuverture<\/strong> (\u00e0 partir de la ligne de commandes ou du menu d\u00e9roulant de VisualARQ). <\/li>\n<li>D\u00e9finissez les <strong>options d&rsquo;insertion<\/strong> de l&rsquo;ouverture dans la bo\u00eete de dialogue. <\/li>\n<li><strong>Ins\u00e9rez<\/strong> l&rsquo;ouverture dans un mur du mod\u00e8le.<\/li>\n<\/ol>\n<p>Apr\u00e8s l&rsquo;insertion de l&rsquo;ouverture vous pouvez trouver qu&rsquo;il est difficile de la s\u00e9lectionner. Il existe une m\u00e9thode simple pour r\u00e9soudre ce probl\u00e8me : <strong>Ajoutez un composant de cadre \u00e0 l&rsquo;ouverture<\/strong> :<\/p>\n<ol>\n<li>Ouvrez la <strong>bo\u00eete de dialogue des Styles d&rsquo;ouverture<\/strong> (tapez vaOuvertureStyle dans la ligne de commande ou, dans le menu VisualARQ, s\u00e9lectionnez Ouverture &gt; Styles d&rsquo;ouverture).<\/li>\n<li>Ajoutez un <strong>cadre<\/strong> au style d&rsquo;ouverture actuel : Cliquez avec le bouton de droite sur le nom du style d&rsquo;ouverture afin d&rsquo;afficher le menu contextuel : s\u00e9lectionnez <em>Nouveau &gt; Cadre d&rsquo;ouverture<\/em><\/li>\n<li>Cliquez sur \u00ab\u00a0<strong>Accepter<\/strong>\u00a0\u00bb ou appuyez sur Entr\u00e9e pour accepter les modifications et fermer la bo\u00eete de dialogue des styles.\u00a0<\/li>\n<\/ol>\n<p>Le composant de cadre appara\u00eetra sur toutes les ouvertures ayant ce style. Les objets des ouvertures sont normalement cr\u00e9\u00e9s sur un calque appel\u00e9 \u00ab\u00a0Ouvertures\u00a0\u00bb*. D\u00e9sactivez ce calque pour cacher tous les composants de cadre d&rsquo;ouverture et activez-le pour s\u00e9lectionner l&rsquo;objet de l&rsquo;ouverture et le modifier.<\/p>\n<img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.visualarq.com\/wp-content\/uploads\/2019\/04\/OpeningStylesDialogNewFrame.png\" alt=\"\" width=\"784\" height=\"545\" class=\"aligncenter size-full wp-image-14288\" srcset=\"https:\/\/www.visualarq.com\/wp-content\/uploads\/2019\/04\/OpeningStylesDialogNewFrame.png 784w, https:\/\/www.visualarq.com\/wp-content\/uploads\/2019\/04\/OpeningStylesDialogNewFrame-300x209.png 300w, https:\/\/www.visualarq.com\/wp-content\/uploads\/2019\/04\/OpeningStylesDialogNewFrame-768x534.png 768w\" sizes=\"(max-width: 784px) 100vw, 784px\" \/>\n<p>(*)Remarque\u00a0: Si le <span style=\"line-height: 24px;\">calque<\/span> \u00ab\u00a0Ouvertures\u00a0\u00bb n&rsquo;est pas cr\u00e9\u00e9 par d\u00e9faut, assignez <span style=\"line-height: 24px;\">le composant de cadre d&rsquo;ouverture \u00e0<\/span> un nouveau calque \u00e0 partir de l&rsquo;onglet \u00ab\u00a0Attributs\u00a0\u00bb apr\u00e8s avoir s\u00e9lectionn\u00e9 ce composant de cadre dans la bo\u00eete de dialogue des styles d&rsquo;ouverture.<\/p>\n<p>&nbsp;<\/p>","protected":false},"featured_media":1863,"parent":0,"menu_order":0,"template":"","meta":{"_et_pb_use_builder":"","_et_pb_old_content":"","_et_gb_content_width":"","footnotes":"","_members_access_role":[],"_members_access_error":""},"tipgroup":[64],"class_list":["post-2350","tip","type-tip","status-publish","has-post-thumbnail","hentry","tipgroup-doors-fr"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Comment cr\u00e9er et s\u00e9lectionner des ouvertures - VisualARQ<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.visualarq.com\/fr\/support\/tip\/how-can-i-create-and-select-openings\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Comment cr\u00e9er et s\u00e9lectionner des ouvertures - VisualARQ\" \/>\n<meta property=\"og:description\" content=\"Le fonctionnement d&rsquo;une ouverture est le m\u00eame que celui d&rsquo;une fen\u00eatre ou une porte. \u00c9tapes pour cr\u00e9er une nouvelle ouverture : Lancer la commande vaOuverture (\u00e0 partir de la ligne de commandes ou du menu d\u00e9roulant de VisualARQ). D\u00e9finissez les options d&rsquo;insertion de l&rsquo;ouverture dans la bo\u00eete de dialogue. Ins\u00e9rez l&rsquo;ouverture dans un mur du [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.visualarq.com\/fr\/support\/tip\/how-can-i-create-and-select-openings\/\" \/>\n<meta property=\"og:site_name\" content=\"VisualARQ\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/visualarq\" \/>\n<meta property=\"article:modified_time\" content=\"2019-04-23T12:57:38+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.visualarq.com\/wp-content\/uploads\/2018\/12\/Opening-Styles-dialog1.png\" \/>\n\t<meta property=\"og:image:width\" content=\"709\" \/>\n\t<meta property=\"og:image:height\" content=\"487\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@VisualARQ\" \/>\n<meta name=\"twitter:label1\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.visualarq.com\\\/fr\\\/support\\\/tip\\\/how-can-i-create-and-select-openings\\\/\",\"url\":\"https:\\\/\\\/www.visualarq.com\\\/fr\\\/support\\\/tip\\\/how-can-i-create-and-select-openings\\\/\",\"name\":\"Comment cr\u00e9er et s\u00e9lectionner des ouvertures - VisualARQ\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.visualarq.com\\\/fr\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.visualarq.com\\\/fr\\\/support\\\/tip\\\/how-can-i-create-and-select-openings\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.visualarq.com\\\/fr\\\/support\\\/tip\\\/how-can-i-create-and-select-openings\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.visualarq.com\\\/wp-content\\\/uploads\\\/2018\\\/12\\\/Opening-Styles-dialog1.png\",\"datePublished\":\"2012-05-08T00:00:00+00:00\",\"dateModified\":\"2019-04-23T12:57:38+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.visualarq.com\\\/fr\\\/support\\\/tip\\\/how-can-i-create-and-select-openings\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.visualarq.com\\\/fr\\\/support\\\/tip\\\/how-can-i-create-and-select-openings\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/www.visualarq.com\\\/fr\\\/support\\\/tip\\\/how-can-i-create-and-select-openings\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.visualarq.com\\\/wp-content\\\/uploads\\\/2018\\\/12\\\/Opening-Styles-dialog1.png\",\"contentUrl\":\"https:\\\/\\\/www.visualarq.com\\\/wp-content\\\/uploads\\\/2018\\\/12\\\/Opening-Styles-dialog1.png\",\"width\":709,\"height\":487},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.visualarq.com\\\/fr\\\/support\\\/tip\\\/how-can-i-create-and-select-openings\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.visualarq.com\\\/fr\\\/home\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Tips\",\"item\":\"https:\\\/\\\/www.visualarq.com\\\/fr\\\/support\\\/tip\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Comment cr\u00e9er et s\u00e9lectionner des ouvertures\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.visualarq.com\\\/fr\\\/#website\",\"url\":\"https:\\\/\\\/www.visualarq.com\\\/fr\\\/\",\"name\":\"VisualARQ\",\"description\":\"Flexible BIM for Rhino\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.visualarq.com\\\/fr\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Comment cr\u00e9er et s\u00e9lectionner des ouvertures - VisualARQ","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.visualarq.com\/fr\/support\/tip\/how-can-i-create-and-select-openings\/","og_locale":"fr_FR","og_type":"article","og_title":"Comment cr\u00e9er et s\u00e9lectionner des ouvertures - VisualARQ","og_description":"Le fonctionnement d&rsquo;une ouverture est le m\u00eame que celui d&rsquo;une fen\u00eatre ou une porte. \u00c9tapes pour cr\u00e9er une nouvelle ouverture : Lancer la commande vaOuverture (\u00e0 partir de la ligne de commandes ou du menu d\u00e9roulant de VisualARQ). D\u00e9finissez les options d&rsquo;insertion de l&rsquo;ouverture dans la bo\u00eete de dialogue. Ins\u00e9rez l&rsquo;ouverture dans un mur du [&hellip;]","og_url":"https:\/\/www.visualarq.com\/fr\/support\/tip\/how-can-i-create-and-select-openings\/","og_site_name":"VisualARQ","article_publisher":"https:\/\/www.facebook.com\/visualarq","article_modified_time":"2019-04-23T12:57:38+00:00","og_image":[{"width":709,"height":487,"url":"https:\/\/www.visualarq.com\/wp-content\/uploads\/2018\/12\/Opening-Styles-dialog1.png","type":"image\/png"}],"twitter_card":"summary_large_image","twitter_site":"@VisualARQ","twitter_misc":{"Dur\u00e9e de lecture estim\u00e9e":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.visualarq.com\/fr\/support\/tip\/how-can-i-create-and-select-openings\/","url":"https:\/\/www.visualarq.com\/fr\/support\/tip\/how-can-i-create-and-select-openings\/","name":"Comment cr\u00e9er et s\u00e9lectionner des ouvertures - VisualARQ","isPartOf":{"@id":"https:\/\/www.visualarq.com\/fr\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.visualarq.com\/fr\/support\/tip\/how-can-i-create-and-select-openings\/#primaryimage"},"image":{"@id":"https:\/\/www.visualarq.com\/fr\/support\/tip\/how-can-i-create-and-select-openings\/#primaryimage"},"thumbnailUrl":"https:\/\/www.visualarq.com\/wp-content\/uploads\/2018\/12\/Opening-Styles-dialog1.png","datePublished":"2012-05-08T00:00:00+00:00","dateModified":"2019-04-23T12:57:38+00:00","breadcrumb":{"@id":"https:\/\/www.visualarq.com\/fr\/support\/tip\/how-can-i-create-and-select-openings\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.visualarq.com\/fr\/support\/tip\/how-can-i-create-and-select-openings\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.visualarq.com\/fr\/support\/tip\/how-can-i-create-and-select-openings\/#primaryimage","url":"https:\/\/www.visualarq.com\/wp-content\/uploads\/2018\/12\/Opening-Styles-dialog1.png","contentUrl":"https:\/\/www.visualarq.com\/wp-content\/uploads\/2018\/12\/Opening-Styles-dialog1.png","width":709,"height":487},{"@type":"BreadcrumbList","@id":"https:\/\/www.visualarq.com\/fr\/support\/tip\/how-can-i-create-and-select-openings\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.visualarq.com\/fr\/home\/"},{"@type":"ListItem","position":2,"name":"Tips","item":"https:\/\/www.visualarq.com\/fr\/support\/tip\/"},{"@type":"ListItem","position":3,"name":"Comment cr\u00e9er et s\u00e9lectionner des ouvertures"}]},{"@type":"WebSite","@id":"https:\/\/www.visualarq.com\/fr\/#website","url":"https:\/\/www.visualarq.com\/fr\/","name":"VisualARQ","description":"Flexible BIM for Rhino","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.visualarq.com\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"}]}},"_links":{"self":[{"href":"https:\/\/www.visualarq.com\/fr\/wp-json\/wp\/v2\/tip\/2350","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.visualarq.com\/fr\/wp-json\/wp\/v2\/tip"}],"about":[{"href":"https:\/\/www.visualarq.com\/fr\/wp-json\/wp\/v2\/types\/tip"}],"version-history":[{"count":0,"href":"https:\/\/www.visualarq.com\/fr\/wp-json\/wp\/v2\/tip\/2350\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.visualarq.com\/fr\/wp-json\/wp\/v2\/media\/1863"}],"wp:attachment":[{"href":"https:\/\/www.visualarq.com\/fr\/wp-json\/wp\/v2\/media?parent=2350"}],"wp:term":[{"taxonomy":"tipgroup","embeddable":true,"href":"https:\/\/www.visualarq.com\/fr\/wp-json\/wp\/v2\/tipgroup?post=2350"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}