{"id":24769,"date":"2020-06-04T11:26:55","date_gmt":"2020-06-04T11:26:55","guid":{"rendered":"https:\/\/www.visualarq.com\/support\/tip\/comment-puis-je-referencer-des-fichiers-externes\/"},"modified":"2022-01-14T12:51:35","modified_gmt":"2022-01-14T12:51:35","slug":"how-can-i-reference-external-files","status":"publish","type":"tip","link":"https:\/\/www.visualarq.com\/fr\/support\/tip\/how-can-i-reference-external-files\/","title":{"rendered":"Comment puis-je r\u00e9f\u00e9rencer des fichiers externes ?"},"content":{"rendered":"<p>La commande <a href=\"https:\/\/docs.mcneel.com\/rhino\/6\/help\/fr-fr\/commands\/insert.htm#Insert\" rel=\"noopener noreferrer\" target=\"_blank\">Ins\u00e9rer<\/a> de Rhino avec l&rsquo;option \u00ab\u00a0Occurrence de bloc\u00a0\u00bb et les sous options \u00ab\u00a0Incrust\u00e9 et li\u00e9\u00a0\u00bb ou \u00ab\u00a0Li\u00e9\u00a0\u00bb permet de r\u00e9f\u00e9rencer des fichiers externes. Les fichiers externes peuvent \u00eatre d&rsquo;autres fichiers de Rhino ou tout autre format pris en charge par Rhino, comme par exemple dwg. Une fois ins\u00e9r\u00e9s, les fichiers sont g\u00e9r\u00e9s \u00e0 travers le <a href=\"https:\/\/docs.mcneel.com\/rhino\/6\/help\/fr-fr\/commands\/block.htm#BlockManager\" rel=\"noopener noreferrer\" target=\"_blank\">Gestionnaire de blocs<\/a>. <\/p>\n\n<p>Il est \u00e9galement possible d&rsquo;utiliser les <strong>Sessions<\/strong> pour travailler \u00e0 plusieurs sur un m\u00eame projet de Rhino. <\/p>\n<hr class=\"separator\">\n<h2>VisualARQ avec fichiers externes r\u00e9f\u00e9renc\u00e9s<\/h2>\n<p><strong>VisualARQ permet de r\u00e9f\u00e9rencer d&rsquo;autres fichiers de Rhino s&rsquo;ils sont ins\u00e9r\u00e9s avec l&rsquo;option \u00ab\u00a0Incrust\u00e9 et li\u00e9\u00a0\u00bb<\/strong>. Si vous choisissez l&rsquo;option \u00ab\u00a0Li\u00e9\u00a0\u00bb, les attributs de section et les repr\u00e9sentation en plan personnalis\u00e9es, entre autres, ne fonctionneront pas. <\/p>\n<img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.visualarq.com\/wp-content\/uploads\/2020\/06\/RhinoInsert.png\" alt=\"Bo\u00eetes de dialogue d'insertion de Rhino : \u00e0 gauche Ins\u00e9rer avec l'option Incrust\u00e9 et li\u00e9 et \u00e0 droite Ins\u00e9rer en tant qu'occurrence de bloc.\" width=\"690\" height=\"468\" class=\"aligncenter size-full wp-image-18906\" srcset=\"https:\/\/www.visualarq.com\/wp-content\/uploads\/2020\/06\/RhinoInsert.png 690w, https:\/\/www.visualarq.com\/wp-content\/uploads\/2020\/06\/RhinoInsert-480x326.png 480w\" sizes=\"(min-width: 0px) and (max-width: 480px) 480px, (min-width: 481px) 690px, 100vw\" \/> \n\n<p>En suivant cette proc\u00e9dure, vous aurez un mod\u00e8le ma\u00eetre dans lequel vous pouvez ins\u00e9rer des parties d&rsquo;un projet d\u00e9velopp\u00e9 par diff\u00e9rentes personnes dans diff\u00e9rents fichiers. <\/p>\n\n<p>Ces fichiers devraient \u00eatre ins\u00e9r\u00e9s dans le mod\u00e8le ma\u00eetre sous forme d&rsquo;occurrences de bloc avec l&rsquo;option \u00ab\u00a0incrust\u00e9 et li\u00e9\u00a0\u00bb. Ensuite lorsqu&rsquo;un utilisateur modifie son fichier et l&rsquo;enregistre, il suffit d&rsquo;aller dans le gestionnaire de blocs du mod\u00e8le ma\u00eetre et d&rsquo;actualiser pour appliquer les modifications. <\/p>\n\n<p>Si des d\u00e9finitions de bloc poss\u00e8dent le m\u00eame nom dans les deux fichiers, Rhino vous demandera lesquelles vous voulez conserver. Si des styles d&rsquo;objets de VisualARQ poss\u00e8dent le m\u00eame nom dans les deux fichiers, ceux du mod\u00e8le ma\u00eetre seront conserv\u00e9s. <\/p>\n\n<div class=\"my-3\"><div style=\"width: 1080px;\" class=\"wp-video\"><video class=\"wp-video-shortcode\" id=\"video-24769-1\" width=\"1080\" height=\"608\" preload=\"metadata\" controls=\"controls\"><source type=\"video\/mp4\" src=\"https:\/\/www.visualarq.com\/wp-content\/uploads\/2020\/06\/VisualARQLinkedModels_nointro_Q45.mp4?_=1\" \/><a href=\"https:\/\/www.visualarq.com\/wp-content\/uploads\/2020\/06\/VisualARQLinkedModels_nointro_Q45.mp4\">https:\/\/www.visualarq.com\/wp-content\/uploads\/2020\/06\/VisualARQLinkedModels_nointro_Q45.mp4<\/a><\/video><\/div><\/div>\n<hr class=\"separator\">\n\n<h2>Sessions de travail<\/h2>\n\n\n<p>Il est \u00e9galement possible d&rsquo;utiliser les Sessions pour travailler \u00e0 plusieurs sur un m\u00eame projet de Rhino. Cette option permet de diviser le projet en plusieurs fichiers de sorte que un utilisateur puisse modifier une partie du projet pendant qu&rsquo;un autre modifie une autre partie. Un fichier ne peut \u00eatre ouvert et modifi\u00e9 que par un seul utilisateur mais plusieurs utilisateurs peuvent le voir.<\/p>\n\n<p>La commande <kbd>Session<\/kbd> ouvre une bo\u00eete de dialogue dans laquelle vous pouvez lier de nouveaux fichiers et passer d&rsquo;un fichier \u00e0 l&rsquo;autre. Le fichier Actif est celui sur lequel vous travaillez alors que les autres utilisateurs peuvent travailler avec les autres fichier li\u00e9s dans la m\u00eame session. <\/p>\n\n<div class=\"my-3\"><iframe loading=\"lazy\" width=\"560\" height=\"315\" src=\"https:\/\/www.youtube.com\/embed\/FI9Jv36E3AM\" title=\"YouTube video player\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture\" allowfullscreen><\/iframe><\/div>","protected":false},"featured_media":2091,"parent":0,"menu_order":0,"template":"","meta":{"_et_pb_use_builder":"","_et_pb_old_content":"","_et_gb_content_width":"","footnotes":"","_members_access_role":[],"_members_access_error":""},"tipgroup":[68],"class_list":["post-24769","tip","type-tip","status-publish","has-post-thumbnail","hentry","tipgroup-files-fr"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Comment puis-je r\u00e9f\u00e9rencer des fichiers externes ? - VisualARQ<\/title>\n<meta name=\"description\" content=\"VisualARQ permet de r\u00e9f\u00e9rencer des fichiers externes gr\u00e2ce \u00e0 la commande Ins\u00e9rer et \u00e0 l&#039;option Lier et incruster. Cette fonction peut \u00eatre utilis\u00e9e pour mieux collaborer.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.visualarq.com\/fr\/support\/tip\/how-can-i-reference-external-files\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Comment puis-je r\u00e9f\u00e9rencer des fichiers externes ? - VisualARQ\" \/>\n<meta property=\"og:description\" content=\"VisualARQ permet de r\u00e9f\u00e9rencer des fichiers externes gr\u00e2ce \u00e0 la commande Ins\u00e9rer et \u00e0 l&#039;option Lier et incruster. Cette fonction peut \u00eatre utilis\u00e9e pour mieux collaborer.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.visualarq.com\/fr\/support\/tip\/how-can-i-reference-external-files\/\" \/>\n<meta property=\"og:site_name\" content=\"VisualARQ\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/visualarq\" \/>\n<meta property=\"article:modified_time\" content=\"2022-01-14T12:51:35+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.visualarq.com\/wp-content\/uploads\/2018\/12\/Tangent-walls-joint.png\" \/>\n\t<meta property=\"og:image:width\" content=\"750\" \/>\n\t<meta property=\"og:image:height\" content=\"452\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@VisualARQ\" \/>\n<meta name=\"twitter:label1\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data1\" content=\"2 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.visualarq.com\\\/fr\\\/support\\\/tip\\\/how-can-i-reference-external-files\\\/\",\"url\":\"https:\\\/\\\/www.visualarq.com\\\/fr\\\/support\\\/tip\\\/how-can-i-reference-external-files\\\/\",\"name\":\"Comment puis-je r\u00e9f\u00e9rencer des fichiers externes ? - VisualARQ\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.visualarq.com\\\/fr\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.visualarq.com\\\/fr\\\/support\\\/tip\\\/how-can-i-reference-external-files\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.visualarq.com\\\/fr\\\/support\\\/tip\\\/how-can-i-reference-external-files\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.visualarq.com\\\/wp-content\\\/uploads\\\/2018\\\/12\\\/Tangent-walls-joint.png\",\"datePublished\":\"2020-06-04T11:26:55+00:00\",\"dateModified\":\"2022-01-14T12:51:35+00:00\",\"description\":\"VisualARQ permet de r\u00e9f\u00e9rencer des fichiers externes gr\u00e2ce \u00e0 la commande Ins\u00e9rer et \u00e0 l'option Lier et incruster. Cette fonction peut \u00eatre utilis\u00e9e pour mieux collaborer.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.visualarq.com\\\/fr\\\/support\\\/tip\\\/how-can-i-reference-external-files\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.visualarq.com\\\/fr\\\/support\\\/tip\\\/how-can-i-reference-external-files\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/www.visualarq.com\\\/fr\\\/support\\\/tip\\\/how-can-i-reference-external-files\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.visualarq.com\\\/wp-content\\\/uploads\\\/2018\\\/12\\\/Tangent-walls-joint.png\",\"contentUrl\":\"https:\\\/\\\/www.visualarq.com\\\/wp-content\\\/uploads\\\/2018\\\/12\\\/Tangent-walls-joint.png\",\"width\":750,\"height\":452},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.visualarq.com\\\/fr\\\/support\\\/tip\\\/how-can-i-reference-external-files\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.visualarq.com\\\/fr\\\/home\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Tips\",\"item\":\"https:\\\/\\\/www.visualarq.com\\\/fr\\\/support\\\/tip\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Comment puis-je r\u00e9f\u00e9rencer des fichiers externes ?\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.visualarq.com\\\/fr\\\/#website\",\"url\":\"https:\\\/\\\/www.visualarq.com\\\/fr\\\/\",\"name\":\"VisualARQ\",\"description\":\"Flexible BIM for Rhino\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.visualarq.com\\\/fr\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Comment puis-je r\u00e9f\u00e9rencer des fichiers externes ? - VisualARQ","description":"VisualARQ permet de r\u00e9f\u00e9rencer des fichiers externes gr\u00e2ce \u00e0 la commande Ins\u00e9rer et \u00e0 l'option Lier et incruster. Cette fonction peut \u00eatre utilis\u00e9e pour mieux collaborer.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.visualarq.com\/fr\/support\/tip\/how-can-i-reference-external-files\/","og_locale":"fr_FR","og_type":"article","og_title":"Comment puis-je r\u00e9f\u00e9rencer des fichiers externes ? - VisualARQ","og_description":"VisualARQ permet de r\u00e9f\u00e9rencer des fichiers externes gr\u00e2ce \u00e0 la commande Ins\u00e9rer et \u00e0 l'option Lier et incruster. Cette fonction peut \u00eatre utilis\u00e9e pour mieux collaborer.","og_url":"https:\/\/www.visualarq.com\/fr\/support\/tip\/how-can-i-reference-external-files\/","og_site_name":"VisualARQ","article_publisher":"https:\/\/www.facebook.com\/visualarq","article_modified_time":"2022-01-14T12:51:35+00:00","og_image":[{"width":750,"height":452,"url":"https:\/\/www.visualarq.com\/wp-content\/uploads\/2018\/12\/Tangent-walls-joint.png","type":"image\/png"}],"twitter_card":"summary_large_image","twitter_site":"@VisualARQ","twitter_misc":{"Dur\u00e9e de lecture estim\u00e9e":"2 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.visualarq.com\/fr\/support\/tip\/how-can-i-reference-external-files\/","url":"https:\/\/www.visualarq.com\/fr\/support\/tip\/how-can-i-reference-external-files\/","name":"Comment puis-je r\u00e9f\u00e9rencer des fichiers externes ? - VisualARQ","isPartOf":{"@id":"https:\/\/www.visualarq.com\/fr\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.visualarq.com\/fr\/support\/tip\/how-can-i-reference-external-files\/#primaryimage"},"image":{"@id":"https:\/\/www.visualarq.com\/fr\/support\/tip\/how-can-i-reference-external-files\/#primaryimage"},"thumbnailUrl":"https:\/\/www.visualarq.com\/wp-content\/uploads\/2018\/12\/Tangent-walls-joint.png","datePublished":"2020-06-04T11:26:55+00:00","dateModified":"2022-01-14T12:51:35+00:00","description":"VisualARQ permet de r\u00e9f\u00e9rencer des fichiers externes gr\u00e2ce \u00e0 la commande Ins\u00e9rer et \u00e0 l'option Lier et incruster. Cette fonction peut \u00eatre utilis\u00e9e pour mieux collaborer.","breadcrumb":{"@id":"https:\/\/www.visualarq.com\/fr\/support\/tip\/how-can-i-reference-external-files\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.visualarq.com\/fr\/support\/tip\/how-can-i-reference-external-files\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.visualarq.com\/fr\/support\/tip\/how-can-i-reference-external-files\/#primaryimage","url":"https:\/\/www.visualarq.com\/wp-content\/uploads\/2018\/12\/Tangent-walls-joint.png","contentUrl":"https:\/\/www.visualarq.com\/wp-content\/uploads\/2018\/12\/Tangent-walls-joint.png","width":750,"height":452},{"@type":"BreadcrumbList","@id":"https:\/\/www.visualarq.com\/fr\/support\/tip\/how-can-i-reference-external-files\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.visualarq.com\/fr\/home\/"},{"@type":"ListItem","position":2,"name":"Tips","item":"https:\/\/www.visualarq.com\/fr\/support\/tip\/"},{"@type":"ListItem","position":3,"name":"Comment puis-je r\u00e9f\u00e9rencer des fichiers externes ?"}]},{"@type":"WebSite","@id":"https:\/\/www.visualarq.com\/fr\/#website","url":"https:\/\/www.visualarq.com\/fr\/","name":"VisualARQ","description":"Flexible BIM for Rhino","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.visualarq.com\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"}]}},"_links":{"self":[{"href":"https:\/\/www.visualarq.com\/fr\/wp-json\/wp\/v2\/tip\/24769","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.visualarq.com\/fr\/wp-json\/wp\/v2\/tip"}],"about":[{"href":"https:\/\/www.visualarq.com\/fr\/wp-json\/wp\/v2\/types\/tip"}],"version-history":[{"count":0,"href":"https:\/\/www.visualarq.com\/fr\/wp-json\/wp\/v2\/tip\/24769\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.visualarq.com\/fr\/wp-json\/wp\/v2\/media\/2091"}],"wp:attachment":[{"href":"https:\/\/www.visualarq.com\/fr\/wp-json\/wp\/v2\/media?parent=24769"}],"wp:term":[{"taxonomy":"tipgroup","embeddable":true,"href":"https:\/\/www.visualarq.com\/fr\/wp-json\/wp\/v2\/tipgroup?post=24769"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}